{"id":157491,"date":"2022-12-16T09:41:50","date_gmt":"2022-12-16T08:41:50","guid":{"rendered":"https:\/\/desdropi.com\/elparque\/batid-moulinex-dd65adce-1000w-s-a-pie-inox\/"},"modified":"2024-05-17T12:59:58","modified_gmt":"2024-05-17T10:59:58","slug":"batid-moulinex-dd65adce-1000w-s-a-pie-inox","status":"publish","type":"product","link":"https:\/\/desdropi.com\/elparque\/batid-moulinex-dd65adce-1000w-s-a-pie-inox\/","title":{"rendered":"Batid. Moulinex Dd65Adce 1000W S\/A Pie Inox"},"content":{"rendered":"<div class=\"descripcion-tab\">\n<p><strong>Control de energ\u00eda<\/strong><\/p>\n<ul>\n<li>Potencia \u279d 1000<\/li>\n<li>Fuente de energ\u00eda \u279d Corriente alterna<\/li>\n<\/ul>\n<p><strong>Empaquetado<\/strong><\/p>\n<ul>\n<li>Tipo de embalaje \u279d Caja<\/li>\n<\/ul>\n<p><strong>Contenido del embalaje<\/strong><\/p>\n<ul>\n<li>Taza de medici\u00f3n \u279d S\u00ed<\/li>\n<\/ul>\n<p><strong>Dise\u00f1o<\/strong><\/p>\n<ul>\n<li>Color del producto \u279d Met\u00e1lico cuarzo, Acero inoxidable<\/li>\n<li>Tipo de batidora \u279d De mano<\/li>\n<li>Taz\u00f3n extraible \u279d S\u00ed<\/li>\n<li>Adherencia suave \u279d S\u00ed<\/li>\n<li>Cuchilla desmontable \u279d S\u00ed<\/li>\n<li>F\u00e1cil de desmontar \u279d S\u00ed<\/li>\n<\/ul>\n<p><strong>Desempe\u00f1o<\/strong><\/p>\n<ul>\n<li>N\u00famero de velocidades \u279d 10<\/li>\n<li>Capacidad del taz\u00f3n \u279d 0,8<\/li>\n<li>Funci\u00f3n de impulso \u279d S\u00ed<\/li>\n<li>Tipo de control \u279d Botones<\/li>\n<li>Tipo de control de velocidad \u279d Paso<\/li>\n<\/ul>\n<p><strong>Caracter\u00edsticas<\/strong><\/p>\n<ul>\n<li>Tipo batidora \u279d De mano<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Control de energ\u00eda Potencia \u279d 1000 Fuente de energ\u00eda \u279d Corriente alterna Empaquetado Tipo de embalaje \u279d Caja Contenido del<\/p>\n","protected":false},"featured_media":157493,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[6500,825,831,851],"product_tag":[],"class_list":{"0":"post-157491","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-de-varilla","7":"product_cat-pequeno-electrodomestico","8":"product_cat-accesorios-de-cocina","9":"product_cat-batidoras-cocina","10":"pa_marca-moulinex","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product\/157491"}],"collection":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/comments?post=157491"}],"version-history":[{"count":0,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product\/157491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/media\/157493"}],"wp:attachment":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/media?parent=157491"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product_cat?post=157491"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product_tag?post=157491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}