{"id":205221,"date":"2023-09-15T11:57:18","date_gmt":"2023-09-15T09:57:18","guid":{"rendered":"https:\/\/desdropi.com\/elparque\/?post_type=product&#038;p=205221"},"modified":"2023-09-15T11:57:18","modified_gmt":"2023-09-15T09:57:18","slug":"instalador-de-termo-electrico-de-30-a-50-litros","status":"publish","type":"product","link":"https:\/\/desdropi.com\/elparque\/instalador-de-termo-electrico-de-30-a-50-litros\/","title":{"rendered":"INSTALADOR DE TERMO EL\u00c9CTRICO DE 30 A 50 LITROS"},"content":{"rendered":"<div class=\"descripcion-tab\">\n<strong>Servicio SOLO DISPONIBLE en la Regi\u00f3n de Murcia.<\/strong><\/p>\n<p>Instalamos el termo el\u00e9ctrico de 30 a 50 litros. Incluye la retirada del viejo.<\/p>\n<p>Se le dar\u00e1<strong>\u00a0cita para la instalaci\u00f3n<\/strong>\u00a0seg\u00fan la demanda en un plazo de\u00a0<strong>24-72 horas.<\/strong>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Servicio SOLO DISPONIBLE en la Regi\u00f3n de Murcia. Instalamos el termo el\u00e9ctrico de 30 a 50 litros. Incluye la retirada<\/p>\n","protected":false},"featured_media":197530,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[6409],"product_tag":[],"class_list":{"0":"post-205221","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-instalaciones","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product\/205221"}],"collection":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/comments?post=205221"}],"version-history":[{"count":0,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product\/205221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/media\/197530"}],"wp:attachment":[{"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/media?parent=205221"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product_cat?post=205221"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/desdropi.com\/elparque\/wp-json\/wp\/v2\/product_tag?post=205221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}